{"id":47114,"date":"2023-09-05T21:32:46","date_gmt":"2023-09-06T01:32:46","guid":{"rendered":"https:\/\/www.scoresandstats.com\/?post_type=gambling-news&#038;p=47114"},"modified":"2025-05-12T21:43:25","modified_gmt":"2025-05-13T01:43:25","slug":"guia-de-apuestas-de-carreras-de-caballos-de-santa-anita","status":"publish","type":"gambling-news","link":"https:\/\/diego-sas.cpp10.com\/es\/gambling-news\/guia-de-apuestas-de-carreras-de-caballos-de-santa-anita\/","title":{"rendered":"Gu\u00eda de apuestas de carreras de caballos de Santa Anita"},"content":{"rendered":"\n<p>Uno de los hip\u00f3dromos m\u00e1s populares de Estados Unidos es el Parque de Santa Anita. Situado en el sur de California, el parque de Santa Anita ofrece carreras de caballos en directo tres veces al a\u00f1o. La temporada de invierno\/primavera comienza a finales de diciembre y se prolonga hasta mediados de junio. El programa de oto\u00f1o de Santa Anita dura 19 d\u00edas, desde finales de septiembre hasta principios de noviembre.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.scoresandstats.com\/es\/casas-apuestas-deportivas\/\" data-type=\"link\" data-id=\"https:\/\/www.scoresandstats.com\/es\/casas-apuestas-deportivas\/\" target=\"_blank\" rel=\"noopener\">MEJORES CASAS DE APUESTAS DEPORTIVAS DEL 2023<\/a><\/strong><\/p>\n\n\n\n<p>El parque de Santa Anita ofrece 10 carreras de grado 1 en invierno y primavera, con tres carreras el d\u00eda de la inauguraci\u00f3n a finales de diciembre. La reuni\u00f3n de oto\u00f1o destaca los Campeonatos Mundiales de la Copa de Criadores (en vivo o simulados) el primer viernes y s\u00e1bado de noviembre. La versi\u00f3n en directo de las carreras de la Copa de Criadores est\u00e1 programada para Santa Anita los d\u00edas 3 y 4 de noviembre de 2023.<\/p>\n\n\n\n<p>Adem\u00e1s de las competitivas carreras de caballos en el hip\u00f3dromo del Parque Santa Anita, hay paquetes para cenar en el restaurante y ofertas especiales de bebidas en el bar, regalos para los aficionados y eventos destacados como parte de las reuniones de invierno, primavera y oto\u00f1o. Las carreras de grado 1 del hip\u00f3dromo del Parque Santa Anita se celebran a lo largo de todo el calendario de carreras previsto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Carreras de caballos de grado 1 en Santa Anita Park<\/h2>\n\n\n\n<p><strong>Invierno\/Primavera<\/strong><\/p>\n\n\n\n<p>La Brea Stakes<\/p>\n\n\n\n<p>Malibu Stakes<\/p>\n\n\n\n<p>American Oaks<\/p>\n\n\n\n<p>Santa Anita Handicap<\/p>\n\n\n\n<p>Frank E. Kilroe Mile<\/p>\n\n\n\n<p>Beholder Mile<\/p>\n\n\n\n<p>Santa Anita Derby<\/p>\n\n\n\n<p>Shoemaker Mile<\/p>\n\n\n\n<p>La Copa de Oro de Hollywood <\/p>\n\n\n\n<p>Gamely Stakes<\/p>\n\n\n\n<p><strong>Oto\u00f1o<\/strong><\/p>\n\n\n\n<p>Awesome Again Stakes<\/p>\n\n\n\n<p>American Pharoah Stakes<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.scoresandstats.com\/es\/noticias-apuestas-deportivas\/guia-de-apuestas-de-carreras-de-caballos-de-saratoga\/\" data-type=\"link\" data-id=\"https:\/\/www.scoresandstats.com\/es\/noticias-apuestas-deportivas\/guia-de-apuestas-de-carreras-de-caballos-de-saratoga\/\" target=\"_blank\" rel=\"noopener\">Gu\u00eda de apuestas de carreras de caballos de Saratoga<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/img.youtube.com\/vi\/wVN7FZ_Kvgk\/hqdefault.jpg\" alt=\"\" title=\"\"><\/figure>\n\n\n\n<p><strong>Campeonato del Mundo de la Copa de Criadores<\/strong><\/p>\n\n\n\n<p>Juvenile Turf Sprint<\/p>\n\n\n\n<p>Juvenile Fillies<\/p>\n\n\n\n<p>Juvenile Fillies Turf<\/p>\n\n\n\n<p>Juvenile Turf<\/p>\n\n\n\n<p>Juvenile<\/p>\n\n\n\n<p>Dirt Mile<\/p>\n\n\n\n<p>Filly &amp; Mare Turf<\/p>\n\n\n\n<p>Filly &amp; Mare Sprint<\/p>\n\n\n\n<p>Mile<\/p>\n\n\n\n<p>Distaff<\/p>\n\n\n\n<p>Turf<\/p>\n\n\n\n<p>Turf Sprint<\/p>\n\n\n\n<p>Sprint<\/p>\n\n\n\n<p>Classic<\/p>\n\n\n\n<p>El invierno en el <a href=\"https:\/\/www.scoresandstats.com\/es\/gambling-news\/guia-de-apuestas-de-carreras-de-caballos-de-santa-anita\/\" target=\"_blank\" rel=\"noopener\">Parque Santa Anita<\/a> comienza con La Brea Stakes, Malibu Stakes y American Oak a finales de diciembre. Todas estas carreras de grado 1 tienen una dotaci\u00f3n de 300.000 $. La Brea Stakes est\u00e1 abierta a potrancas de tres a\u00f1os y es una carrera al sprint de siete estadios sobre tierra. Los Malibu Stakes est\u00e1n abiertos a potros (y potrancas) de tres a\u00f1os y la carrera sprint de siete millas tambi\u00e9n se corre sobre tierra. El American Oaks se corre a 1\u00bc millas sobre hierba y est\u00e1 abierto a potrancas de tres a\u00f1os.<\/p>\n\n\n\n<p>La siguiente carrera de Grado 1 se disputa en marzo y se llama Santa Anita Handicap. El premio es de 500.000 $ y la carrera est\u00e1 abierta a caballos de cuatro a\u00f1os o m\u00e1s. El Santa Anita Handicap tiene un recorrido de 1,25 millas sobre tierra. Esta carrera fue una de las m\u00e1s importantes de Norteam\u00e9rica en la temporada de carreras de invierno.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.scoresandstats.com\/es\/noticias-apuestas-deportivas\/guia-de-apuestas-de-carreras-de-caballos-de-churchill-downs\/\" data-type=\"link\" data-id=\"https:\/\/www.scoresandstats.com\/es\/noticias-apuestas-deportivas\/guia-de-apuestas-de-carreras-de-caballos-de-churchill-downs\/\" target=\"_blank\" rel=\"noopener\">Gu\u00eda de apuestas de carreras de caballos de Churchill Downs<\/a><\/strong><\/p>\n\n\n\n<p>El Derby de Santa Anita, una de las principales carreras de preparaci\u00f3n para el recorrido del Derby de Kentucky, es una de las \u00faltimas carreras de primavera para caballos pura sangre de tres a\u00f1os. Se celebra a principios de abril, la bolsa de premios asciende a 750.000 d\u00f3lares y los puntos de calidad son de los m\u00e1s altos para el Derby de Kentucky. La carrera se disputa sobre tierra y tiene una distancia de 1 1\/8 millas.<\/p>\n\n\n\n<p>La Copa de Oro de Hollywood se celebra en el parque Santa Anita a finales de mayo. Esta carrera de Grado 1 est\u00e1 abierta a caballos pura sangre de tres a\u00f1os o m\u00e1s. La Copa de Oro de Hollywood tiene un recorrido de 1,25 millas sobre tierra y est\u00e1 dotada con 400.000 $.<\/p>\n\n\n\n<p>La reuni\u00f3n de oto\u00f1o del parque Santa Anita incluye los Awesome Again Stakes a finales de septiembre y los American Pharoah Stakes a principios de octubre. Estas carreras de grado 1 son clasificatorias autom\u00e1ticas para la Copa de Criadores a principios de noviembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de los hip\u00f3dromos m\u00e1s populares de Estados Unidos es el Parque de Santa Anita. Situado en el sur de California, el<\/p>\n","protected":false},"author":14,"featured_media":243471,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"news-category":[542],"news-tag":[],"class_list":["post-47114","gambling-news","type-gambling-news","status-publish","has-post-thumbnail","hentry","news-category-how-to-es","resize-featured-image"],"acf":[],"_links":{"self":[{"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/gambling-news\/47114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/gambling-news"}],"about":[{"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/types\/gambling-news"}],"author":[{"embeddable":true,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/users\/14"}],"version-history":[{"count":2,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/gambling-news\/47114\/revisions"}],"predecessor-version":[{"id":157766,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/gambling-news\/47114\/revisions\/157766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/media\/243471"}],"wp:attachment":[{"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/media?parent=47114"}],"wp:term":[{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/news-category?post=47114"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/news-tag?post=47114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}