{"id":257063,"date":"2025-03-28T23:54:43","date_gmt":"2025-03-29T03:54:43","guid":{"rendered":"https:\/\/www.scoresandstats.com\/?post_type=blog&#038;p=257063"},"modified":"2025-06-03T14:43:25","modified_gmt":"2025-06-03T18:43:25","slug":"gent-wevelgem-cuotas-predicciones","status":"publish","type":"blog","link":"https:\/\/diego-sas.cpp10.com\/es\/blog\/gent-wevelgem-cuotas-predicciones\/","title":{"rendered":"2025 Gent-Wevelgem Cuotas, Predicciones y C\u00f3mo Ver"},"content":{"rendered":"\n<div class=\"gb-element-403aebf9\">\n<div class=\"wp-block-rank-math-toc-block\" id=\"rank-math-toc\"><h2>Tabla de contenidos<\/h2><nav><ul><li class=\"\"><a href=\"#how-to-watch-the-gent-wevelgem\">\u00bfC\u00f3mo ver el Gent-Wevelgem?<\/a><\/li><li class=\"\"><a href=\"#gent-wevelgem-route\">Recorrido del Gent-Wevelgem<\/a><\/li><li class=\"\"><a href=\"#gent-wevelgem-odds\">Cuotas del Gent-Wevelgem<\/a><\/li><li class=\"\"><a href=\"#gent-wevelgem-favorites\">Favoritos del Gent-Wevelgem<\/a><\/li><li class=\"\"><a href=\"#the-best-gent-wevelgem-betting-value\">Mejor apuesta con valor<\/a><\/li><li class=\"\"><a href=\"#the-top-gent-wevelgem-longshot\">Tapado del Gent-Wevelgem<\/a><\/li><li class=\"\"><a href=\"#gent-wevelgem-predictions\">Predicciones del Gent-Wevelgem<\/a><\/li><li class=\"\"><a href=\"#gent-wevelgem-results\">Resultados del Gent-Wevelgem<\/a><\/li><\/ul><\/nav><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n<div class=\"gb-container gb-container-3f49f52b cta-banner\">\n<div class=\"gb-container gb-container-850afe40\">\n\n<figure class=\"gb-block-image gb-block-image-187e1edf\"><img loading=\"lazy\" decoding=\"async\" width=\"175\" height=\"23\" class=\"gb-image gb-image-187e1edf\" src=\"https:\/\/www.scoresandstats.com\/app\/uploads\/2024\/10\/sas-logo.png\" alt=\"\" title=\"sas logo\"><\/figure>\n\n<\/div>\n\n<div class=\"gb-container gb-container-9c9424aa\">\n<div class=\"gb-container gb-container-5e656e58\">\n\n<p class=\"gb-headline gb-headline-eea3b9ca gb-headline-text\">Visita a los mejores de la industria<\/p>\n\n\n\n<p class=\"gb-headline gb-headline-6e2778d4 gb-headline-text\">Membres\u00eda de handicapping<br>\u00a1Para m\u00e1s pron\u00f3sticos de ciclismo!<\/p>\n\n<\/div>\n\n<div class=\"gb-container gb-container-4ba00e92\">\n\n<a class=\"gb-button gb-button-fd51bf78 gb-button-text\" href=\"https:\/\/www.scoresandstats.com\/es\/registro\/\" target=\"_blank\" rel=\"noopener\">Prueba gratuita<\/a>\n\n<\/div>\n<\/div>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p>El domingo 30 de marzo se pone en marcha la 87.<sup>a<\/sup> edici\u00f3n de la Gent-Wevelgem desde la Puerta de Menin en Ypres, Flandes (B\u00e9lgica). Esta cl\u00e1sica es la tercera de las cinco pruebas que conforman la Semana Ciclista Flamenca, la cual concluye el domingo 6 de abril con el Tour de Flandes.<\/p>\n\n\n\n<p>El primer evento fue la <a href=\"https:\/\/www.scoresandstats.com\/es\/blog-category\/cycling\/\" target=\"_blank\" rel=\"noopener\">cl\u00e1sica<\/a> <a href=\"https:\/\/www.scoresandstats.com\/es\/blog\/clasico-brugge-de-panne-2025-cuotas-predicciones\/\" target=\"_blank\" rel=\"noopener\">Brugge-De Panne<\/a>, que result\u00f3 una aut\u00e9ntica guerra de desgaste el mi\u00e9rcoles 26 de marzo.<\/p>\n\n\n\n<p>A falta de 6,5 km se produjeron tres aparatosas ca\u00eddas que destrozaron el pelot\u00f3n y Juan Sebasti\u00e1n Molano super\u00f3 por foto finish a mi elegido Jonathan Milan.<\/p>\n\n\n\n<p>El segundo evento fue la <a href=\"https:\/\/www.scoresandstats.com\/es\/blog\/e3-saxo-classic-cuotas-predicciones\/\" target=\"_blank\" rel=\"noopener\">E3 Saxo Bank Classic<\/a> el viernes 28 de marzo. Mathieu van der Poel se march\u00f3 en solitario los \u00faltimos 30 km y gan\u00f3 por segundo a\u00f1o consecutivo, haci\u00e9ndome quedar muy bien con mi pron\u00f3stico.<\/p>\n\n\n\n<p>Mads Pedersen acab\u00f3 segundo en el E3 con una gran actuaci\u00f3n y aparece como favorito para ganar la Gent-Wevelgem 2025. Jonathan Milan, Tim Merlier y Jasper Philipsen acompa\u00f1an a Pedersen entre los favoritos previos.<\/p>\n\n\n\n<p>La cuarta prueba de la semana es la Dwars door Vlaanderen, el mi\u00e9rcoles 2 de abril. A\u00fan no se conocen los favoritos, pero es probable que varios corredores repitan despu\u00e9s de la Gent-Wevelgem.<\/p>\n\n\n\n<p>Dicho esto, repasemos las \u00faltimas cuotas de ciclismo, cortes\u00eda de los <a href=\"https:\/\/www.scoresandstats.com\/es\/casas-apuestas-deportivas\/\" target=\"_blank\" rel=\"noopener\">mejores sitios de apuestas<\/a>, y lancemos nuestros pron\u00f3sticos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"how-to-watch-the-gent-wevelgem\">\u00bfC\u00f3mo ver el Gent-Wevelgem?<\/h2>\n\n\n\n<p>Para la audiencia internacional, TNT Sports y Eurosport retransmitir\u00e1n la carrera en directo desde B\u00e9lgica. En Norteam\u00e9rica, la plataforma MAX ofrecer\u00e1 la prueba en streaming, igual que hizo con la E3 Saxo Classic.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"gent-wevelgem-route\">Recorrido del Gent-Wevelgem<\/h2>\n\n\n\n<p>Aunque el nombre incluya \u201cGent\u201d, la salida ya no es all\u00ed. El pelot\u00f3n parte frente a la Puerta de Menin en Ypres, memorial a las v\u00edctimas de la I Guerra Mundial, y recorrer\u00e1 250 km por Flandes hasta la meta en Vanackerestraat (Wevelgem).<\/p>\n\n\n\n<p>El trazado de esta edici\u00f3n es casi 3 km m\u00e1s corto que el del a\u00f1o pasado. Las cotas no llegan hasta que restan 100 km, pero antes los corredores afrontar\u00e1n fuertes vientos de costado rumbo a la costa.<\/p>\n\n\n\n<p>La ruta incluye <a href=\"https:\/\/www.cyclingnews.com\/races\/gent-wevelgem-2025\/map\/\" target=\"_blank\" rel=\"noopener\">las siguientes subidas<\/a>, con varias ascensiones repetidas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Scherpenberg a 147.9 km<\/li>\n\n\n\n<li>Baneberg a 156.7 km<\/li>\n\n\n\n<li>Monteberg a 162.2 km<\/li>\n\n\n\n<li>Kemmelberg (Belvedere) a 164.4 km<\/li>\n\n\n\n<li>Monteberg a 192.7 km<\/li>\n\n\n\n<li>Kemmelberg a 194.5 km<\/li>\n\n\n\n<li>Scherpenberg a 202 km<\/li>\n\n\n\n<li>Baneberg a 210.7 km<\/li>\n\n\n\n<li>Kemmelberg (Ossuaire) a 216 km<\/li>\n<\/ul>\n\n\n\n<p>Tras la \u00faltima cota, con una pendiente m\u00e1xima del 21,1 %, restar\u00e1n 34 km llanos hasta meta. Lo m\u00e1s probable es un sprint final si hay varios corredores colaborando.<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Gent-Wevelgem | Eight of the most windy editions in #GW history\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/FJH7jh-HOf4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"gent-wevelgem-odds\">Cuotas del Gent-Wevelgem<\/h2>\n\n\n\n<p>Revisa las \u00faltimas cuotas para la Gent-Wevelgem:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Cuotas de ciclismo<\/th><th class=\"has-text-align-center\" data-align=\"center\">Cuotas de ciclismo<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Mads Pedersen (+225)<\/td><td class=\"has-text-align-center\" data-align=\"center\">Jonathan Milan (+400)<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Jasper Philipsen (+800)<\/td><td class=\"has-text-align-center\" data-align=\"center\">Tim Merlier (+800)<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Olav Kooij (+1800)<\/td><td class=\"has-text-align-center\" data-align=\"center\">Jasper Stuyven (+2000)<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Jordie Meeus (+2500)<\/td><td class=\"has-text-align-center\" data-align=\"center\">Biniam Girmay (+2500)<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Laurence Pithie (+3300)<\/td><td class=\"has-text-align-center\" data-align=\"center\">Soren Waerenskjold (+3300)<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Mathias Vacek (+3300)<\/td><td class=\"has-text-align-center\" data-align=\"center\">Paul Magnier (+3300)<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Michael Matthews (+4000)<\/td><td class=\"has-text-align-center\" data-align=\"center\">Tom Skujins (+4000)<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Matteo Trentin (+5000)<\/td><td class=\"has-text-align-center\" data-align=\"center\">Arnaud De Lie (+5000)<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Mads Pedersen aparece como m\u00e1ximo favorito para la carrera de este fin de semana, con Jonathan Milan a la estela. M\u00e1s atr\u00e1s, aunque a distancia, asoman Jasper Philipsen y Tim Merlier.<\/p>\n\n\n\n<p>Despu\u00e9s de Merlier, hay un gran salto hasta el siguiente grupo de corredores: Olav Kooij, Jasper Stuyven y Biniam Girmay.&nbsp;Sigue leyendo a continuaci\u00f3n para ver a qui\u00e9n pronostico como ganador de esta carrera y si coincide con lo que los <a href=\"https:\/\/www.scoresandstats.com\/best-handicappers\/\" target=\"_blank\" rel=\"noopener\">mejores handicappers<\/a> est\u00e1n pronosticando.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"gent-wevelgem-favorites\">Favoritos del Gent-Wevelgem<\/h2>\n\n\n\n<p>Veamos a los favoritos para la 87.<sup>a<\/sup> edici\u00f3n de la Gent-Wevelgem:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mads Pedersen (+225)&nbsp;&nbsp;&nbsp;&nbsp;<\/h3>\n\n\n\n<p>Mads Pedersen ha continuado su gran temporada. Fue el \u00fanico que pudo aguantar la rueda de Van der Poel en la E3 antes de ceder y acabar segundo en los \u00faltimos 20&nbsp;km. Eso no empa\u00f1a su actuaci\u00f3n, fue la revancha de lo sucedido el a\u00f1o pasado cuando gan\u00f3 la Gent-Wevelgem superando a MVDP al esprint.<\/p>\n\n\n\n<p>En mi previo de la E3 Saxo Classic dije lo siguiente sobre Pedersen:<\/p>\n\n\n\n<p><em>\u00abLa forma de Pedersen esta temporada me hace confiar en que puede meterse en el Top&nbsp;10. Y si logra aguantar con los dos favoritos, no me sorprender\u00eda verle en el podio\u00bb.<\/em><\/p>\n\n\n\n<p>Eso fue exactamente lo que pas\u00f3: termin\u00f3 en el podio como subcampe\u00f3n. Otra gran actuaci\u00f3n para el dan\u00e9s, que ya suma dos victorias este a\u00f1o y un 7.<sup>o<\/sup> en la <a href=\"https:\/\/www.scoresandstats.com\/es\/blog\/milan-san-remo-probabilidades-cuotas\/\" target=\"_blank\" rel=\"noopener\">Mil\u00e1n-San Remo<\/a>.<\/p>\n\n\n\n<p>Adem\u00e1s de ganar la Gent-Wevelgem el a\u00f1o pasado, Pedersen tambi\u00e9n la conquist\u00f3 en 2020. Busca convertirse en el s\u00e9ptimo ciclista con tres victorias en la prueba.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Jonathan Milan (+400)<\/h3>\n\n\n\n<p>Jonathan Milan se qued\u00f3 a cent\u00edmetros de hacerme quedar muy bien y ponerme 2-0 en la Semana Flamenca. Por desgracia, acab\u00f3 2.<sup>o<\/sup> en la Classic Brugge-De Panne.<\/p>\n\n\n\n<p>Aun as\u00ed, eso solo refuerza su gran a\u00f1o. Al igual que Tim Merlier, Milan tambi\u00e9n suma seis triunfos en la temporada, adem\u00e1s de dos clasificaciones por puntos.<\/p>\n\n\n\n<p>El italiano de 24&nbsp;a\u00f1os empez\u00f3 con dos victorias de etapa y un segundo puesto en la clasificaci\u00f3n por puntos de la Volta a la Comunitat Valenciana.<\/p>\n\n\n\n<p>Luego gan\u00f3 otras dos etapas y el maillot verde en el UAE Tour, sumando cuatro podios en total.<\/p>\n\n\n\n<p>Posteriormente, el corredor del Lidl-Trek se llev\u00f3 dos etapas y la clasificaci\u00f3n por puntos en la <a href=\"https:\/\/www.scoresandstats.com\/es\/blog\/tirreno-adriatico-predicciones\/\" target=\"_blank\" rel=\"noopener\">Tirreno-Adri\u00e1tico<\/a>, incluyendo un 5.<sup>o<\/sup> en la contrarreloj inicial, prueba de su velocidad.<\/p>\n\n\n\n<p>El a\u00f1o pasado termin\u00f3 5.<sup>o<\/sup> en la Gent-Wevelgem, su mejor resultado en tres participaciones. Si supera las cotas y evita ca\u00eddas, Milan puede mejorar esa posici\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"HE IS INEVITABLE \ud83e\udd29 Jonathan Milan WINS the final stage of Tirenno-Adriatico \ud83e\udd47\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/FLau0LhUrmc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Jasper Philipsen (+800)&nbsp;&nbsp;&nbsp;<\/h3>\n\n\n\n<p>Jasper Philipsen tuvo una mala actuaci\u00f3n en la Classic Brugge-De Panne pese a ser uno de los favoritos para lograr el triplete. Termin\u00f3 47.<sup>o<\/sup> tras verse envuelto en una ca\u00edda.<\/p>\n\n\n\n<p>Esa actuaci\u00f3n se sum\u00f3 a otras dos discretas: 163.<sup>o<\/sup> en la Mil\u00e1n-San Remo y abandono en la Danilith Nokere Koerse tras una ca\u00edda.<\/p>\n\n\n\n<p>Antes de esos tropiezos, el esprinter del Alpecin-Deceuninck hab\u00eda ganado en Kuurne-Bruselas-Kuurne y fue tercero en la <a href=\"https:\/\/www.scoresandstats.com\/es\/blog\/omloop-het-nieuwsblad-cuotas-predicciones\/\" target=\"_blank\" rel=\"noopener\">Omloop Het Nieuwsblad<\/a> el 1&nbsp;de marzo.<\/p>\n\n\n\n<p>Esta ser\u00e1 su sexta Gent-Wevelgem. Fue 15.<sup>o<\/sup> el a\u00f1o pasado, lejos de su mejor resultado (4.<sup>o<\/sup> en 2023). Antes de eso no hab\u00eda pasado del 25.\u00ba puesto.<\/p>\n\n\n\n<p>Philipsen tiene la velocidad para plantar cara a Merlier y Milan, pero no s\u00e9 si est\u00e1 en la forma necesaria para batirlos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tim Merlier (+800)<\/h3>\n\n\n\n<p>Al igual que Milan, Tim Merlier es uno de los mejores esprinters del a\u00f1o. El belga comenz\u00f3 con dos victorias y un segundo puesto en la clasificaci\u00f3n por puntos en el AlUla Tour.<\/p>\n\n\n\n<p>Despu\u00e9s sum\u00f3 otras dos etapas y fue tercero en la clasificaci\u00f3n por puntos del UAE Tour.<\/p>\n\n\n\n<p>Pero eso no fue todo: tambi\u00e9n se llev\u00f3 dos etapas en <a href=\"https:\/\/www.scoresandstats.com\/es\/blog\/paris-nice-predicciones-2025\/\" target=\"_blank\" rel=\"noopener\">Par\u00eds-Niza<\/a>. As\u00ed, lleg\u00f3 como favorito a la Classic Brugge-De Panne, donde una ca\u00edda le oblig\u00f3 a abandonar.<\/p>\n\n\n\n<p>Merlier no corri\u00f3 la E3 porque necesit\u00f3 puntos en la rodilla tras la ca\u00edda. Si est\u00e1 recuperado, su velocidad le da una gran opci\u00f3n en la \u00fanica cl\u00e1sica que realmente puede ganar si est\u00e1 al cien por cien.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"the-best-gent-wevelgem-betting-value\">Mejor apuesta con valor<\/h2>\n\n\n\n<p>Estos corredores ofrecen valor seg\u00fan sus cuotas actuales, su inicio de temporada y su historial en la carrera:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Olav Kooij (+1800)<\/h3>\n\n\n\n<p>Me han impresionado las actuaciones de Olav Kooij este a\u00f1o, incluso sin tantas victorias. Por ejemplo, fue 2.<sup>o<\/sup> en Kuurne-Bruselas-Kuurne tras Philipsen.<\/p>\n\n\n\n<p>En el Tour de Om\u00e1n se llev\u00f3 dos etapas y termin\u00f3 segundo en la clasificaci\u00f3n por puntos. Kooij tambi\u00e9n gan\u00f3 una etapa en la Tirreno-Adri\u00e1tico, con tres Top&nbsp;5 y tercero en la general por puntos.<\/p>\n\n\n\n<p>Cre\u00eda que Kooij pelear\u00eda por la victoria en Brugge, pero tambi\u00e9n sufri\u00f3 una ca\u00edda.<\/p>\n\n\n\n<p>Seg\u00fan el director deportivo de Visma, Grischa Niermann, sus lesiones no le impedir\u00e1n correr este fin de semana:<\/p>\n\n\n\n<p><em>\u00abComo equipo \u00edbamos bien colocados, pero la ca\u00edda fue inevitable. El final era demasiado peligroso. Olav tambi\u00e9n se fue al suelo, pero parece que solo tiene raspones. Quedan grandes objetivos y veremos c\u00f3mo se recupera\u00bb.<\/em><\/p>\n\n\n\n<p>Kooij ofrece gran valor: tiene la velocidad y un equipo capaz de lanzar el esprint. Si est\u00e1 recuperado y evita problemas, puede luchar algo m\u00e1s que el podio.<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Olav Kooij sprints to first season victory | HIGHLIGHTS Tour of Oman stage 1\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/haAsmSZddyI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Biniam Girmay (+2500)<\/h3>\n\n\n\n<p>En 2022, Biniam Girmay sorprendi\u00f3 al mundo ganando la Gent-Wevelgem. Desde entonces se ha convertido en uno de los ciclistas m\u00e1s populares, pero este a\u00f1o parece falto de su mejor forma.<\/p>\n\n\n\n<p>Acaba de ser 22.<sup>o<\/sup> en la E3, peor que el 14.<sup>o<\/sup> en la Mil\u00e1n-San Remo. Parece contar con menos apoyo y un puntito menos que los favoritos.<\/p>\n\n\n\n<p>Aun as\u00ed, si Girmay va a enderezar la temporada ser\u00e1 aqu\u00ed, donde ya sabe lo que es ganar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"the-top-gent-wevelgem-longshot\">Tapado del Gent-Wevelgem<\/h2>\n\n\n\n<p>Michael Matthews (+4000) es mi elecci\u00f3n como gran tapado para la Gent-Wevelgem 2025. Tambi\u00e9n lo fue para la E3, donde termin\u00f3 27.<sup>o<\/sup> en el grupo perseguidor al igual que Girmay.<\/p>\n\n\n\n<p>Aun as\u00ed, fue 4.<sup>o<\/sup> en la Mil\u00e1n-San Remo y 2.<sup>o<\/sup> en la etapa&nbsp;3 de Par\u00eds-Niza.<\/p>\n\n\n\n<p>Matthews disputar\u00e1 su sexta Gent-Wevelgem. Su mejor resultado fue 5.<sup>o<\/sup> en 2021; el a\u00f1o pasado acab\u00f3 62.<sup>o<\/sup>.<\/p>\n\n\n\n<p>La mejor oportunidad de Matthews es marcar a Pedersen y seguir al dan\u00e9s cada vez que ataque. Si Matthews muestra un estado de forma de primer nivel, esos \u00faltimos 34&nbsp;km de la Gent-Wevelgem podr\u00edan ser el escenario en el que el australiano logre una gran sorpresa.<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"FULL RACE: 2024 Gent-Wevelgem - Men\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/qSnE3obXEu4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"gent-wevelgem-predictions\">Predicciones del Gent-Wevelgem<\/h2>\n\n\n\n<p>Philipsen, Milan, Merlier y Kooij tienen la velocidad suficiente para ganar esta carrera y, si todo se decide en un esprint masivo, podr\u00edamos ver al hombre m\u00e1s r\u00e1pido imponerse. El estado f\u00edsico de Merlier me preocupa: no creo que est\u00e9 al 100 % tras su fea ca\u00edda en Brugge.<\/p>\n\n\n\n<p>Philipsen a\u00fan no ha mostrado su mejor forma y dudo que tenga ahora mismo la velocidad necesaria para batir a Milan al esprint. Eso podr\u00eda cambiar en las Grandes Vueltas.<\/p>\n\n\n\n<p>Para m\u00ed, esta carrera se decide entre Milan, el hombre m\u00e1s r\u00e1pido; Kooij, que cuenta con uno de los mejores equipos; y el defensor del t\u00edtulo, Pedersen.<\/p>\n\n\n\n<p>Me gustar\u00eda ver ganar a Kooij y Milan est\u00e1 deseando volver a la bicicleta y lograr una victoria tras lo ocurrido en De Panne. Dicho esto, me quedo con Pedersen y su equipo, que har\u00e1n todo lo posible para evitar un esprint masivo.<\/p>\n\n\n\n<p>Espero un ritmo alto desde el inicio y que Pedersen ataque en las \u00faltimas cotas para marcharse en solitario y ganar la carrera.<\/p>\n\n\n\n<div class=\"gb-element-fc595fde\">\n<pre class=\"wp-block-verse\"><strong>Bet: Mads Pedersen (+225)<\/strong><\/pre>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"gent-wevelgem-results\">Resultados del Gent-Wevelgem<\/h2>\n\n\n\n<p>Seis corredores comparten el r\u00e9cord de m\u00e1s victorias en la Gent-Wevelgem, con tres triunfos cada uno: Robert Van Eenaeme, Rik Van Looy, el gran Eddy Merckx, Mario Cipollini, Tom Boonen y Peter Sagan.<\/p>\n\n\n\n<p>El dan\u00e9s Mads Pedersen es el \u00fanico corredor en activo con dos victorias, incluida la edici\u00f3n de 2024. B\u00e9lgica domina el palmar\u00e9s con 50 triunfos, seguida de Italia con siete.<\/p>\n\n\n\n<p>A continuaci\u00f3n, la lista de los \u00faltimos ganadores de la Gent-Wevelgem:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">A\u00f1o<\/th><th class=\"has-text-align-center\" data-align=\"center\">Ganador<\/th><th class=\"has-text-align-center\" data-align=\"center\">Equipo<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">2024&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">Mads Pedersen<\/td><td class=\"has-text-align-center\" data-align=\"center\">Lidl-Trek<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2023&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">Christophe Laporte<\/td><td class=\"has-text-align-center\" data-align=\"center\">Team Jumbo\u2013Visma<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">Biniam Girmay<\/td><td class=\"has-text-align-center\" data-align=\"center\">Intermarch\u00e9\u2013Wanty\u2013Gobert Mat\u00e9riaux<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2021&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">Wout van Aert<\/td><td class=\"has-text-align-center\" data-align=\"center\">Team Jumbo\u2013Visma<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2020&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">Mads Pedersen<\/td><td class=\"has-text-align-center\" data-align=\"center\">Trek\u2013Segafredo<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2019&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">Alexander Kristoff<\/td><td class=\"has-text-align-center\" data-align=\"center\">UAE Team Emirates<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2018&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">Peter Sagan<\/td><td class=\"has-text-align-center\" data-align=\"center\">Bora-Hansgrohe<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2017&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">Greg Van Avermaet<\/td><td class=\"has-text-align-center\" data-align=\"center\">BMC Racing Team<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2016&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">Peter Sagan<\/td><td class=\"has-text-align-center\" data-align=\"center\">Tinkoff<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2015&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">Luca Paolini<\/td><td class=\"has-text-align-center\" data-align=\"center\">Team Katusha<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2014&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/td><td class=\"has-text-align-center\" data-align=\"center\">John Degenkolb<\/td><td class=\"has-text-align-center\" data-align=\"center\">Giant-Shimano<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visita a los mejores de la industria Membres\u00eda de handicapping\u00a1Para m\u00e1s pron\u00f3sticos de ciclismo! El domingo 30 de marzo se pone en<\/p>\n","protected":false},"author":37,"featured_media":219855,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"blog-category":[1296],"blog-tag":[],"class_list":["post-257063","blog","type-blog","status-publish","has-post-thumbnail","hentry","blog-category-cycling","resize-featured-image"],"acf":[],"_links":{"self":[{"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/blog\/257063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/users\/37"}],"version-history":[{"count":1,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/blog\/257063\/revisions"}],"predecessor-version":[{"id":257070,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/blog\/257063\/revisions\/257070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/media\/219855"}],"wp:attachment":[{"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/media?parent=257063"}],"wp:term":[{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/blog-category?post=257063"},{"taxonomy":"blog-tag","embeddable":true,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/blog-tag?post=257063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}