{"id":257040,"date":"2024-07-14T15:24:18","date_gmt":"2024-07-14T19:24:18","guid":{"rendered":"https:\/\/www.scoresandstats.com\/?post_type=blog&#038;p=257040"},"modified":"2025-06-03T14:09:06","modified_gmt":"2025-06-03T18:09:06","slug":"nba-summer-league-cuotas-predicciones","status":"publish","type":"blog","link":"https:\/\/diego-sas.cpp10.com\/es\/blog\/nba-summer-league-cuotas-predicciones\/","title":{"rendered":"2024 NBA Summer League Cuotas y Predicciones"},"content":{"rendered":"<div class=\"gb-container gb-container-48ce4bfe\">\n\n<div class=\"wp-block-rank-math-toc-block\" id=\"rank-math-toc\"><h2>Table of Contents<\/h2><nav><ul><li><a href=\"#2024-nba-summer-league-championship-odds\">Cuotas al campeonato de la NBA Summer League 2024<\/a><\/li><li><a href=\"#why-are-the-golden-state-warriors-the-betting-favorite\">\u00bfPor qu\u00e9 los Golden State Warriors son el favorito en las apuestas?<\/a><\/li><li><a href=\"#top-2024-nba-summer-league-contenders\">Principales contendientes de la NBA Summer League 2024<\/a><ul><li><a href=\"#houston-rockets-1000\">Houston Rockets +1000<\/a><\/li><\/ul><\/li><li><a href=\"#best-2024-nba-summer-league-value-bet\">Mejor apuesta de valor en la NBA Summer League 2024<\/a><\/li><li><a href=\"#2024-nba-summer-league-prediction\">Pron\u00f3stico para la NBA Summer League 2024<\/a><\/li><\/ul><\/nav><\/div>\n\n<\/div>\n\n\n<div style=\"height:41px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>No lo pierdas de vista: \u00a1ya puedes apostar al ganador de la NBA Summer League 2024! Las cuotas est\u00e1n oficialmente disponibles en los <a href=\"https:\/\/www.scoresandstats.com\/es\/casas-apuestas-deportivas\/\" target=\"_blank\" rel=\"noopener\">sitios de apuestas en l\u00ednea<\/a>, con el torneo de Las Vegas arrancando esta semana.<\/p>\n\n\n\n<p>Los <a href=\"https:\/\/www.scoresandstats.com\/teams\/basketball\/nba\/golden-state-warriors\/\" target=\"_blank\" rel=\"noopener\">Golden State Warriors<\/a> llegan como favoritos, pero este mercado es, por naturaleza, vol\u00e1til.<\/p>\n\n\n\n<p>M\u00e1s all\u00e1 de los equipos, los apostadores querr\u00e1n evaluar al talento joven \u2013sobre todo a los novatos\u2013. Se espera la participaci\u00f3n de la mayor\u00eda de las selecciones altas del Draft 2024, mientras algunos novatos del a\u00f1o pasado tambi\u00e9n buscan impresionar.<\/p>\n\n\n\n<p>\u00bfDebes respaldar a los Dubs o hay otros equipos con valor? Con los rookies cambiando el panorama de las apuestas, analizar\u00e9 el campo y te ayudar\u00e9 a decidir c\u00f3mo apostar este verano.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"2024-nba-summer-league-championship-odds\">Cuotas al campeonato de la NBA Summer League 2024<\/h2>\n\n\n\n<p>El primer paso antes de apostar es revisar las cuotas. Bet365 es la \u00fanica casa que he visto con mercado para campe\u00f3n de Summer League, as\u00ed que la usamos de referencia.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\"><strong>Cuotas NBA Summer League 2024<\/strong><\/th><th class=\"has-text-align-center\" data-align=\"center\"><strong>Cuotas NBA Summer League 2024<\/strong><\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Golden State Warriors +600<\/td><td class=\"has-text-align-center\" data-align=\"center\">Utah Jazz +700<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Memphis Grizzlies +800<\/td><td class=\"has-text-align-center\" data-align=\"center\">Houston Rockets +1000<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Minnesota Timberwolves +1000<\/td><td class=\"has-text-align-center\" data-align=\"center\">Charlotte Hornets +1600<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Philadelphia 76ers +1600<\/td><td class=\"has-text-align-center\" data-align=\"center\">Boston Celtics +1800<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Cleveland Cavaliers +1800<\/td><td class=\"has-text-align-center\" data-align=\"center\">Orlando Magic +1800<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Indiana Pacers +2000<\/td><td class=\"has-text-align-center\" data-align=\"center\">Sacramento Kings +2000<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Washington Wizards +2000<\/td><td class=\"has-text-align-center\" data-align=\"center\">Atlanta Hawks +2500<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Portland Trail Blazers +2500<\/td><td class=\"has-text-align-center\" data-align=\"center\">Toronto Raptors +2500<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Estas no son todas las cuotas disponibles, pero muestran a cada equipo con +2500 o mejor. Si quieres ver a las 30 franquicias, visita Bet365 o compara precios.<\/p>\n\n\n\n<p>Para las casas, los equipos no listados tienen pocas probabilidades reales de pelear por el t\u00edtulo.<\/p>\n\n\n\n<p>Claro, si uno de esos clubes destaca, tal vez lo incluya al hablar de valor. Al fin y al cabo, esto es Summer League: literalmente puede pasar cualquier cosa.<\/p>\n\n\n\n<p>Eso significa que virtualmente todos est\u00e1n en juego, aunque conviene vigilar de cerca a quienes poseen las mejores <a href=\"https:\/\/www.scoresandstats.com\/es\/resultados-y-lineas\/basquetbol\/nba\/\" target=\"_blank\" rel=\"noopener\">cuotas NBA<\/a>.<\/p>\n\n\n\n<p>Dicho esto, hagamos una pausa para ver por qu\u00e9 los Dubs encabezan el listado y qu\u00e9 otros contendientes sobresalen este verano.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"why-are-the-golden-state-warriors-the-betting-favorite\">\u00bfPor qu\u00e9 los Golden State Warriors son el favorito en las apuestas?<\/h2>\n\n\n\n<p>Por las cuotas, cualquiera pensar\u00eda que Steph Curry va a jugar. Pero los Dubs ya cambiaron por completo y, por supuesto, ninguna de sus estrellas pisar\u00e1 la duela en julio.<\/p>\n\n\n\n<p>Adem\u00e1s, Chef Curry estar\u00e1 ocupado en Par\u00eds 2024. (Siempre puedes apostar al baloncesto ol\u00edmpico si lo prefieres).<\/p>\n\n\n\n<p>Tu foco principal, sin embargo, es determinar si vale la pena apostar a que Golden State levante el t\u00edtulo.<\/p>\n\n\n\n<p>Lo entiendo hasta cierto punto: los Dubs contar\u00e1n con j\u00f3venes ya probados como Jonathan Kuminga, Trayce Jackson-Davis y Brandin Podziemski. Kuminga explot\u00f3 en su tercer a\u00f1o con 16.1 puntos por juego y un lugar fijo en el quinteto.<\/p>\n\n\n\n<p>Podziemski tambi\u00e9n brill\u00f3 como novato y fue gran raz\u00f3n de que la franquicia dejara marchar a Klay Thompson.<\/p>\n\n\n<div class=\"gb-container gb-container-a9889830\">\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">13 years. Four championships. Countless iconic moments.<br><br>Thank you for everything, <a href=\"https:\/\/twitter.com\/KlayThompson?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@KlayThompson<\/a>. <a href=\"https:\/\/t.co\/6kFZmWHFbu\">pic.twitter.com\/6kFZmWHFbu<\/a><\/p>&mdash; Golden State Warriors (@warriors) <a href=\"https:\/\/twitter.com\/warriors\/status\/1809618559267451167?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 6, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n<\/div>\n\n\n<p>Ese tr\u00edo quiz\u00e1 no suene tan temible frente al resto, pero para Summer League es un aut\u00e9ntico \u201cstack\u201d.<\/p>\n\n\n\n<p>Nadie sobresale como favorito absoluto, pero al evaluar talento y experiencia, es f\u00e1cil entender por qu\u00e9 los Warriors son el equipo a vencer.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"top-2024-nba-summer-league-contenders\">Principales contendientes de la NBA Summer League 2024<\/h2>\n\n\n\n<p>Ya lo dijimos: tener cuota +600 no te convierte en favorito leg\u00edtimo. Golden State me gusta, pero hay muchos equipos con cuotas atractivas.<\/p>\n\n\n\n<p>Aqu\u00ed tienes otros tres que destacan como contendientes reales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"utah-jazz-700\">Utah Jazz +700<\/h3>\n\n\n\n<p>Si hablamos de talento que viaja a Las Vegas, no puedo omitir a los <a href=\"https:\/\/www.scoresandstats.com\/teams\/basketball\/nba\/utah-jazz\/\" target=\"_blank\" rel=\"noopener\">Utah Jazz<\/a>, poseedores de la segunda mejor cuota.<\/p>\n\n\n\n<p>Utah presenta a Keyonte George como base franquicia y al p\u00edvot Walker Kessler.<\/p>\n\n\n\n<p>Y si eso fuera poco, a\u00f1ade a Brice Sensabaugh, Taylor Hendricks y a los novatos Cody Williams, Isaiah Collier y Kyle Filipowski.<\/p>\n\n\n\n<p>Filipowski ha sido famoso por los motivos equivocados, as\u00ed que busca cambiar la narrativa.<\/p>\n\n\n<div class=\"gb-container gb-container-103103d9\">\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">The Kyle Filipowski story is BIZARRE. Groomed by your older Mormon gf who was originally your babysitter &amp; made you write a goodbye letter to break up with your family??<br><br>When you\u2019re 7 feet tall and as gifted as he is, dropping that far must mean that he\u2019s brainwashed as fuck <a href=\"https:\/\/t.co\/YPuxidCAm5\">pic.twitter.com\/YPuxidCAm5<\/a><\/p>&mdash; KFC (@KFCBarstool) <a href=\"https:\/\/twitter.com\/KFCBarstool\/status\/1806507435005288836?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">June 28, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n<\/div>\n\n\n<p>Williams fue un gran acierto en el pick 10 del Draft y quiz\u00e1 sea su jugador m\u00e1s intrigante este verano.<\/p>\n\n\n\n<p>En definitiva, Utah tiene talento de sobra y es una amenaza clara al t\u00edtulo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"memphis-grizzlies-800\">Memphis Grizzlies +800<\/h3>\n\n\n\n<p>Otro equipo repleto de talento que llega a Las Vegas son los Memphis Grizzlies. No, no contar\u00e1n con Ja Morant, pero a\u00fan as\u00ed disponen de un mont\u00f3n de piezas \u00fatiles.<\/p>\n\n\n\n<p>El gigante novato Zach Edey es, sin duda, la gran atracci\u00f3n y ya caus\u00f3 una grata impresi\u00f3n durante la acci\u00f3n previa a la Summer League de Las Vegas.<\/p>\n\n\n\n<p>Edey deber\u00eda brillar \u2013e incluso dominar\u2013 en Las Vegas, pero no est\u00e1 solo. GG Jackson, Scotty Pippen Jr. y Jake LaRavia quiz\u00e1 no sean nombres de renombre, pero el a\u00f1o pasado sumaron mucha experiencia en la NBA.<\/p>\n\n\n\n<p>Estos j\u00f3venes demostraron que pertenecen a la liga en cierta medida y esperan que una carrera profunda en la Summer League ayude a consolidar un lugar permanente al m\u00e1ximo nivel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"houston-rockets-1000\">Houston Rockets +1000<\/h3>\n\n\n\n<p>Podr\u00eda enumerar varias plantillas de Summer League repletas de talento, pero terminar\u00eda nombrando pr\u00e1cticamente a todos los equipos.<\/p>\n\n\n\n<p>En su lugar, cerrar\u00e9 mis principales aspirantes con los <a href=\"https:\/\/www.scoresandstats.com\/teams\/basketball\/nba\/houston-rockets\/\" target=\"_blank\" rel=\"noopener\">Houston Rockets<\/a>, que cuentan con la tercera selecci\u00f3n del Draft 2024, Reed Sheppard.<\/p>\n\n\n\n<p>El exjugador de Kentucky deslumbr\u00f3 en la NCAA, mostrando una habilidad de creaci\u00f3n \u00e9lite y, a\u00fan mejor, tiro exterior (52&nbsp;% en triples la temporada pasada).<\/p>\n\n\n\n<p>Sheppard es, sin duda, el jugador a seguir si eres fan de Houston y una gran raz\u00f3n por la que tienen opciones de ganar el t\u00edtulo. Aunque su arsenal ofensivo es divertido, lo que m\u00e1s impresiona es su tenacidad defensiva.<\/p>\n\n\n\n<p>No lo har\u00e1 todo solo. La leyenda de la Summer League Cam Whitmore regresa por m\u00e1s, mientras que Jermaine Samuels Jr., Kira Lewis Jr. y Orland Robinson son rotaciones NBA que aportar\u00e1n.<\/p>\n\n\n\n<p>El nivel de talento y experiencia no es el mismo que el de los equipos antes mencionados, pero eso ya se refleja en sus atractivas cuotas de +1000.<\/p>\n\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"gb-container gb-container-3f49f52b cta-banner\">\n<div class=\"gb-container gb-container-850afe40\">\n\n<figure class=\"gb-block-image gb-block-image-187e1edf\"><img loading=\"lazy\" decoding=\"async\" width=\"175\" height=\"23\" class=\"gb-image gb-image-187e1edf\" src=\"https:\/\/www.scoresandstats.com\/app\/uploads\/2024\/10\/sas-logo.png\" alt=\"\" title=\"sas logo\"><\/figure>\n\n<\/div>\n\n<div class=\"gb-container gb-container-9c9424aa\">\n<div class=\"gb-container gb-container-5e656e58\">\n\n<p class=\"gb-headline gb-headline-eea3b9ca gb-headline-text\">Suscr\u00edbete para apostar con \u00e9xito en la NBA<\/p>\n\n\n\n<p class=\"gb-headline gb-headline-6e2778d4 gb-headline-text\">Membres\u00eda de Handicapping<\/p>\n\n<\/div>\n\n<div class=\"gb-container gb-container-4ba00e92\">\n\n<a class=\"gb-button gb-button-fd51bf78 gb-button-text\" href=\"https:\/\/www.scoresandstats.com\/es\/registro\/\" target=\"_blank\" rel=\"noopener\">Prueba gratuita<\/a>\n\n<\/div>\n<\/div>\n<\/div>\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"best-2024-nba-summer-league-value-bet\">Mejor apuesta de valor en la NBA Summer League 2024<\/h2>\n\n\n\n<p>Existen varias apuestas de valor interesantes al elegir al campe\u00f3n de la Summer League 2024.<\/p>\n\n\n\n<p>Donovan Clingan hace que los <a href=\"https:\/\/www.scoresandstats.com\/teams\/basketball\/nba\/portland-trail-blazers\/\" target=\"_blank\" rel=\"noopener\">Portland Trail Blazers<\/a> sean tentadores a +2500, mientras siempre estar\u00e1 la narrativa de Bronny James con los <a href=\"https:\/\/www.scoresandstats.com\/teams\/basketball\/nba\/los-angeles-lakers\/\" target=\"_blank\" rel=\"noopener\">Los Angeles Lakers<\/a> (+7500).<\/p>\n\n\n\n<p>Apostar solo a los <a href=\"https:\/\/www.scoresandstats.com\/es\/blog\/bronny-james-predicciones\/\" target=\"_blank\" rel=\"noopener\">props de Bronny<\/a> es divertido, pero incluirlo con toda la franquicia quiz\u00e1 sea menos arriesgado. Por supuesto, tambi\u00e9n est\u00e1n los <a href=\"https:\/\/www.scoresandstats.com\/teams\/basketball\/nba\/new-orleans-pelicans\/\" target=\"_blank\" rel=\"noopener\">New Orleans Pelicans<\/a>, quienes ofrecen las mejores cuotas.<\/p>\n\n\n\n<p>De todas las opciones de valor, ninguna destaca m\u00e1s que los Washington Wizards.<\/p>\n\n\n\n<p>Ya s\u00e9 que no suelen inspirar confianza para ganar nada, pero f\u00e1cilmente podr\u00edan ser el equipo con m\u00e1s talento en Las Vegas.<\/p>\n\n\n\n<p>Washington acaba de seleccionar al atl\u00e9tico p\u00edvot Alex Sarr con el pick dos.<\/p>\n\n\n<div class=\"gb-container gb-container-fe99b759\">\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">The Washington Wizards select Alexandre Sarr with the No. 2 Pick in the 2024 NBA Draft.<a href=\"https:\/\/twitter.com\/hashtag\/NBADraft?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#NBADraft<\/a> <a href=\"https:\/\/t.co\/mZQugPoRYo\">pic.twitter.com\/mZQugPoRYo<\/a><\/p>&mdash; No Ceilings (@NoCeilingsNBA) <a href=\"https:\/\/twitter.com\/NoCeilingsNBA\/status\/1806120005052092904?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">June 27, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n<\/div>\n\n\n<p>Se une a veteranos infravalorados que quieren demostrar su val\u00eda.<\/p>\n\n\n\n<p>Est\u00e1 por verse cu\u00e1n involucrado est\u00e9 el novato, pero posee el tama\u00f1o y la atletismo para ser una bestia en ambos extremos. Sin olvidar a Johnny Davis, Jared Butler y Tristan Vukcevic, quienes ya mostraron cosas en SL o incluso en la NBA.<\/p>\n\n\n\n<p>Washington no tiene el mismo reconocimiento que otros, pero si prestas atenci\u00f3n, su plantel impresiona. Si no temes al riesgo, es mi sleeper favorito para 2024.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"2024-nba-summer-league-prediction\">Pron\u00f3stico para la NBA Summer League 2024<\/h2>\n\n\n\n<p>Creo que los Warriors merecen el favoritismo. Su cuota de +600 es justa para un equipo con tanta experiencia y talento.<\/p>\n\n\n\n<p>No obstante, el talento de Utah es ligeramente mejor y me gustan sus novatos. El inside\/outside de Keyonte George y Walker Kessler ya seduce, pero Cody Williams y compa\u00f1\u00eda los impulsan a\u00fan m\u00e1s.<\/p>\n\n\n\n<p>Como dije, puedes ir en muchas direcciones: cada opci\u00f3n viable paga +600 o m\u00e1s.<\/p>\n\n\n\n<p>Yo empezar\u00eda con Utah y centrar\u00eda mis apuestas en los contendientes analizados. Si buscas una cuota m\u00e1s alta, mirar\u00eda primero a Washington.<\/p>\n\n\n<div class=\"gb-container gb-container-2c2824b6\">\n\n<pre class=\"wp-block-verse\"><strong><em>Apuesta: Utah Jazz +700<\/em><\/strong><\/pre>\n\n<\/div>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No lo pierdas de vista: \u00a1ya puedes apostar al ganador de la NBA Summer League 2024! Las cuotas est\u00e1n oficialmente disponibles en<\/p>\n","protected":false},"author":36,"featured_media":257044,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"blog-category":[1251],"blog-tag":[],"class_list":["post-257040","blog","type-blog","status-publish","has-post-thumbnail","hentry","blog-category-nba","resize-featured-image"],"acf":[],"_links":{"self":[{"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/blog\/257040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/users\/36"}],"version-history":[{"count":2,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/blog\/257040\/revisions"}],"predecessor-version":[{"id":257049,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/blog\/257040\/revisions\/257049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/media\/257044"}],"wp:attachment":[{"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/media?parent=257040"}],"wp:term":[{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/blog-category?post=257040"},{"taxonomy":"blog-tag","embeddable":true,"href":"https:\/\/diego-sas.cpp10.com\/es\/wp-json\/wp\/v2\/blog-tag?post=257040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}